{"id":1,"date":"2023-08-09T07:15:10","date_gmt":"2023-08-09T07:15:10","guid":{"rendered":"https:\/\/www.guptadocumentcentre.com\/blog\/?p=1"},"modified":"2023-08-09T07:15:10","modified_gmt":"2023-08-09T07:15:10","slug":"hello-world","status":"publish","type":"post","link":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/","title":{"rendered":"Hello world!"},"content":{"rendered":"\n<p>Welcome to WordPress. This is your first post. Edit or delete it, then start writing!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Welcome to WordPress. This is your first post. Edit or delete it, then start writing!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hello world!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hello world!\" \/>\n<meta property=\"og:description\" content=\"Welcome to WordPress. This is your first post. Edit or delete it, then start writing!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/\" \/>\n<meta property=\"og:site_name\" content=\"guptadocumentcentre\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-09T07:15:10+00:00\" \/>\n<meta name=\"author\" content=\"team_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"team_admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/\"},\"author\":{\"name\":\"team_admin\",\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/person\/609e79bde85cf7b9f98dd394a46c6968\"},\"headline\":\"Hello world!\",\"datePublished\":\"2023-08-09T07:15:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/\"},\"wordCount\":17,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#organization\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/\",\"url\":\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/\",\"name\":\"Hello world!\",\"isPartOf\":{\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#website\"},\"datePublished\":\"2023-08-09T07:15:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.guptadocumentcentre.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hello world!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#website\",\"url\":\"https:\/\/www.guptadocumentcentre.com\/blog\/\",\"name\":\"guptadocumentcentre\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.guptadocumentcentre.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#organization\",\"name\":\"guptadocumentcentre\",\"url\":\"https:\/\/www.guptadocumentcentre.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.guptadocumentcentre.com\/blog\/wp-content\/uploads\/2023\/08\/logo-gupta.png\",\"contentUrl\":\"https:\/\/www.guptadocumentcentre.com\/blog\/wp-content\/uploads\/2023\/08\/logo-gupta.png\",\"width\":196,\"height\":70,\"caption\":\"guptadocumentcentre\"},\"image\":{\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/person\/609e79bde85cf7b9f98dd394a46c6968\",\"name\":\"team_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/61d5e24cc55eed9e87e252af23b3dad4ccb1e5e7ce41c6c35d8707acf0d58b87?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/61d5e24cc55eed9e87e252af23b3dad4ccb1e5e7ce41c6c35d8707acf0d58b87?s=96&d=mm&r=g\",\"caption\":\"team_admin\"},\"sameAs\":[\"https:\/\/www.guptadocumentcentre.com\/blog\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hello world!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/","og_locale":"en_US","og_type":"article","og_title":"Hello world!","og_description":"Welcome to WordPress. This is your first post. Edit or delete it, then start writing!","og_url":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/","og_site_name":"guptadocumentcentre","article_published_time":"2023-08-09T07:15:10+00:00","author":"team_admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"team_admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/#article","isPartOf":{"@id":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/"},"author":{"name":"team_admin","@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/person\/609e79bde85cf7b9f98dd394a46c6968"},"headline":"Hello world!","datePublished":"2023-08-09T07:15:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/"},"wordCount":17,"commentCount":0,"publisher":{"@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#organization"},"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/","url":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/","name":"Hello world!","isPartOf":{"@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#website"},"datePublished":"2023-08-09T07:15:10+00:00","breadcrumb":{"@id":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.guptadocumentcentre.com\/blog\/hello-world\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.guptadocumentcentre.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Hello world!"}]},{"@type":"WebSite","@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#website","url":"https:\/\/www.guptadocumentcentre.com\/blog\/","name":"guptadocumentcentre","description":"","publisher":{"@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.guptadocumentcentre.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#organization","name":"guptadocumentcentre","url":"https:\/\/www.guptadocumentcentre.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-content\/uploads\/2023\/08\/logo-gupta.png","contentUrl":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-content\/uploads\/2023\/08\/logo-gupta.png","width":196,"height":70,"caption":"guptadocumentcentre"},"image":{"@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/person\/609e79bde85cf7b9f98dd394a46c6968","name":"team_admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.guptadocumentcentre.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/61d5e24cc55eed9e87e252af23b3dad4ccb1e5e7ce41c6c35d8707acf0d58b87?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61d5e24cc55eed9e87e252af23b3dad4ccb1e5e7ce41c6c35d8707acf0d58b87?s=96&d=mm&r=g","caption":"team_admin"},"sameAs":["https:\/\/www.guptadocumentcentre.com\/blog"]}]}},"_links":{"self":[{"href":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":0,"href":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guptadocumentcentre.com\/blog\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}